{"id":19065,"date":"2023-11-07T14:36:31","date_gmt":"2023-11-07T19:36:31","guid":{"rendered":"https:\/\/leger360.com\/cookie-policy\/"},"modified":"2025-08-11T02:52:25","modified_gmt":"2025-08-11T06:52:25","slug":"politique-de-gestion-des-temoins","status":"publish","type":"page","link":"https:\/\/leger360.com\/fr\/politique-de-gestion-des-temoins\/","title":{"rendered":"Politique de gestion des t\u00e9moins"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00a0\u00bb1&Prime; admin_label=\u00a0\u00bbsection\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_row admin_label=\u00a0\u00bbrow\u00a0\u00bb _builder_version=\u00a0\u00bb4.16&Prime; background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb][et_pb_column type=\u00a0\u00bb4_4&Prime; _builder_version=\u00a0\u00bb4.16&Prime; custom_padding=\u00a0\u00bb|||\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb custom_padding__hover=\u00a0\u00bb|||\u00a0\u00bb][et_pb_text _builder_version=\u00a0\u00bb4.27.4&Prime; _module_preset=\u00a0\u00bb10548b23-6ede-4eab-a654-510ad96b6d29&Prime; global_colors_info=\u00a0\u00bb{}\u00a0\u00bb hover_enabled=\u00a0\u00bb0&Prime; sticky_enabled=\u00a0\u00bb0&Prime; width=\u00a0\u00bb45%\u00a0\u00bb]<\/p>\n<h1><span style=\"color: #ed1c2f;\">Politique <\/span>de gestion des t\u00e9moins<\/h1>\n<p>[\/et_pb_text][et_pb_text admin_label=\u00a0\u00bbText\u00a0\u00bb _builder_version=\u00a0\u00bb4.24.2&Prime; text_font=\u00a0\u00bbAptos||||||||\u00a0\u00bb header_font_size=\u00a0\u00bb40px\u00a0\u00bb header_2_font=\u00a0\u00bbAptos||||||||\u00a0\u00bb header_2_font_size=\u00a0\u00bb20px\u00a0\u00bb header_3_font=\u00a0\u00bb|600|||||||\u00a0\u00bb background_size=\u00a0\u00bbinitial\u00a0\u00bb background_position=\u00a0\u00bbtop_left\u00a0\u00bb background_repeat=\u00a0\u00bbrepeat\u00a0\u00bb global_colors_info=\u00a0\u00bb{}\u00a0\u00bb]<\/p>\n<h2 class=\"wp-block-heading\" id=\"h-date-d-entree-en-vigueur-7-fevrier-2024\">DATE D\u2019ENTR\u00c9E EN VIGUEUR : 7 F\u00c9VRIER 2024<\/h2>\n<p>1.0<span>\u00a0<\/span><strong>D\u00c9CLARATION DE POLITIQUE EN MATI\u00c8RE DE T\u00c9MOINS<\/strong><\/p>\n<p>Marketing L\u00e9ger Inc. et ses filiales (\u00ab L\u00e9ger \u00bb) utilise diff\u00e9rents t\u00e9moins de connexion (aussi appel\u00e9s sous le terme anglais \u00ab cookies \u00bb) ou des technologies similaires sur ses sites Web qui sont n\u00e9cessaires pour leur bon fonctionnement mais aussi pour am\u00e9liorer leur performance, bonifier votre exp\u00e9rience, mesurer l\u2019audience et int\u00e9grer des services permettant d\u2019am\u00e9liorer l\u2019interactivit\u00e9 de ces sites. Si vous naviguez sur ces sites, ces t\u00e9moins seront install\u00e9s sur votre navigateur Web.<\/p>\n<p>La pr\u00e9sente Politique sur les t\u00e9moins de connexion explique comment nous utilisons ces t\u00e9moins et s\u2019applique aux sites Web. Elle pr\u00e9cise aussi les types de t\u00e9moins de connexion que nous utilisons, pourquoi nous les utilisons et comment vous pouvez modifier vos pr\u00e9f\u00e9rences en mati\u00e8re de t\u00e9moins de connexion.<\/p>\n<p>Nous vous conseillons de lire la pr\u00e9sente politique en parall\u00e8le avec notre<span>\u00a0<\/span><a href=\"\/fr\/privacy-policy\">politique de confidentialit\u00e9<\/a><span>\u00a0<\/span>qui indique comment nous collectons, utilisons et traitons vos renseignements personnels.<\/p>\n<h3 class=\"wp-block-heading\">2.0<span>\u00a0<\/span><strong>D\u00c9FINITION<\/strong><\/h3>\n<ul>\n<li><strong>\u00ab\u00a0T\u00e9moin de connexion\u00a0\u00bb :<span>\u00a0<\/span><\/strong>Un petit fichier texte, contenant des informations, stock\u00e9 dans votre appareil (votre ordinateur, t\u00e9l\u00e9phone cellulaire, tablette, etc.) par un site Web (sur lequel vous vous connectez) et qui est associ\u00e9 \u00e0 un domaine Internet (c\u2019est-\u00e0-dire dans la majorit\u00e9 des cas \u00e0 l\u2019ensemble des pages d\u2019un m\u00eame site web). Ce fichier est automatiquement renvoy\u00e9 lors de contacts ult\u00e9rieurs avec le m\u00eame domaine. Les t\u00e9moins de connexion aideront le domaine Internet, ou un autre domaine Internet, \u00e0 reconna\u00eetre votre appareil lors de votre prochaine visite. Dans la pr\u00e9sente politique, nous utilisons le terme \u00ab\u00a0t\u00e9moin\u00a0\u00bb pour d\u00e9signer tous les fichiers qui collectent des renseignements de cette fa\u00e7on.<\/li>\n<li><strong>\u00ab\u00a0T\u00e9moins internes\u00a0\u00bb\u00a0:<\/strong><span>\u00a0<\/span>Ce sont des t\u00e9moins qui sont d\u00e9pos\u00e9s par le site consult\u00e9 par l\u2019utilisateur, plus pr\u00e9cis\u00e9ment sur le domaine du site. Ils peuvent \u00eatre utilis\u00e9s pour le bon fonctionnement du site ou pour d\u2019autres finalit\u00e9s, notamment publicitaires.<\/li>\n<li><strong>\u00ab\u00a0T\u00e9moins tiers\u00a0\u00bb\u00a0:<span>\u00a0<\/span><\/strong>Ce sont les t\u00e9moins d\u00e9pos\u00e9s sur des domaines diff\u00e9rents de celui visit\u00e9 par l\u2019utilisateur. Ces t\u00e9moins \u00ab tiers \u00bb sont g\u00e9n\u00e9ralement g\u00e9r\u00e9s par des tiers qui ont \u00e9t\u00e9 interrog\u00e9s par le site Web visit\u00e9 et non par l\u2019utilisateur lui-m\u00eame. Ces t\u00e9moins peuvent aussi \u00eatre n\u00e9cessaires au bon fonctionnement du site Web, mais ils servent majoritairement \u00e0 permettre au tiers de voir quelles pages ont \u00e9t\u00e9 visit\u00e9es sur le site Web en question par un utilisateur et de collecter des informations sur lui, notamment \u00e0 des fins publicitaires. Nous n\u2019avons pas acc\u00e8s aux technologies de ces tiers et n\u2019avons aucun contr\u00f4le dessus. Nous ne lions pas les donn\u00e9es recueillies par des tiers aux renseignements personnels de nos clients ou de nos utilisateurs.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading\">3.0<span>\u00a0<\/span><strong>\u00c0 QUOI NOUS SERVENT LES T\u00c9MOINS ?<\/strong><\/h3>\n<p>Les t\u00e9moins ne causent aucun dommage \u00e0 votre appareil, mais permettent plus facilement, par exemple, de retrouver des pr\u00e9f\u00e9rences, de pr\u00e9remplir certains champs et d\u2019adapter le contenu de nos sites Web. Nous utilisons donc les t\u00e9moins \u00e0 diverses fins, notamment pour :<\/p>\n<ul>\n<li>M\u00e9moriser la langue d\u2019affichage de la page Web ;<\/li>\n<li>Retenir vos pr\u00e9f\u00e9rences et analyser le fonctionnement de nos sites Web ;<\/li>\n<li>Am\u00e9liorer la fonctionnalit\u00e9 ou la performance de nos sites Web ;<\/li>\n<li>Nous aider \u00e0 comprendre comment nos sites Web sont utilis\u00e9s afin de les am\u00e9liorer ;<\/li>\n<li>Vous recommander du contenu que nous croyons \u00eatre le plus appropri\u00e9 pour vous ;<\/li>\n<li>Tracer votre navigation \u00e0 des fins statistiques ou publicitaires ;<\/li>\n<li>Etc.<\/li>\n<\/ul>\n<p>Certains des usages des t\u00e9moins sont strictement n\u00e9cessaires aux fonctionnalit\u00e9s des sites Web express\u00e9ment demand\u00e9es par l\u2019utilisateur ou bien \u00e0 l\u2019\u00e9tablissement de la communication et donc exempt\u00e9s de consentement. D\u2019autres usages, qui ne correspondent pas \u00e0 ces crit\u00e8res, n\u00e9cessitent votre consentement.<\/p>\n<p>Lors de votre navigation sur nos sites Web, une banni\u00e8re sur la gestion des t\u00e9moins s\u2019affichera vous permettant d\u2019activer ou non les t\u00e9moins qui ne sont pas strictement n\u00e9cessaires au bon fonctionnement de nos sites Web.<\/p>\n<h3 class=\"wp-block-heading\">4.0<span>\u00a0<\/span><strong>QUELS RENSEIGNEMENTS SONT RECUEILLIS AVEC LES T\u00c9MOINS ?<\/strong><\/h3>\n<p>Les renseignements suivants sont recueillis au moyen de t\u00e9moins :<\/p>\n<ul>\n<li>votre adresse IP ;<\/li>\n<li>votre fournisseur de services Internet ;<\/li>\n<li>le jour et l\u2019heure de d\u00e9but et de fin de votre visite ;<\/li>\n<li>la langue de votre navigateur ;<\/li>\n<li>la r\u00e9gion ou la municipalit\u00e9, d\u00e9termin\u00e9e d\u2019apr\u00e8s l\u2019adresse IP ;<\/li>\n<li>le type et la version de votre navigateur ;<\/li>\n<li>le type et la version de votre syst\u00e8me d\u2019exploitation ;<\/li>\n<li>le type et le mod\u00e8le de votre appareil (t\u00e9l\u00e9phone, tablette ou ordinateur) ;<\/li>\n<li>le domaine du site pr\u00e9c\u00e9dent visit\u00e9 ;<\/li>\n<li>l\u2019adresse des pages visit\u00e9es sur les sites Web ;<\/li>\n<li>vos activit\u00e9s (par exemple : clic, d\u00e9filement de l\u2019\u00e9cran) sur le site Web de L\u00e9ger ;<\/li>\n<li>le point d\u2019origine de votre visite ;<\/li>\n<li>la r\u00e9solution d\u2019\u00e9cran de l\u2019appareil que vous utilisez.<\/li>\n<\/ul>\n<h3 class=\"wp-block-heading\">5.0<span>\u00a0<\/span><strong>COMBIEN DE TEMPS LES T\u00c9MOINS SONT-ILS STOCK\u00c9S SUR MON APPAREIL ?<\/strong><\/h3>\n<p>Un t\u00e9moin peut \u00eatre temporaire ou permanent. Les t\u00e9moins temporaires sont stock\u00e9s temporairement sur votre appareil pendant que vous utilisez les sites Web, puis supprim\u00e9s lorsque vous fermez votre navigateur Internet. Les t\u00e9moins permanents restent sur votre appareil pour une certaine dur\u00e9e une fois votre navigateur Internet ferm\u00e9. La dur\u00e9e pendant laquelle un cookie permanent est stock\u00e9 sur votre appareil varie. Ces t\u00e9moins stock\u00e9s nous permettent de savoir que vous avez d\u00e9j\u00e0 visit\u00e9 l\u2019un de nos sites Web ou d\u2019enregistrer vos pr\u00e9f\u00e9rences.<\/p>\n<h3 class=\"wp-block-heading\">6.0<span>\u00a0<\/span><strong>QUELS TYPES DE T\u00c9MOINS SONT D\u00c9POS\u00c9S PAR NOS SITES WEB ?<\/strong><\/h3>\n<p>Chaque type de t\u00e9moin a une finalit\u00e9 diff\u00e9rente. Nous utilisons les types de t\u00e9moins suivants :<\/p>\n<ul>\n<li>Les t\u00e9moins strictement n\u00e9cessaires,<\/li>\n<li>Les t\u00e9moins de fonctionnalit\u00e9,<\/li>\n<li>Les t\u00e9moins de r\u00e9seaux sociaux,<\/li>\n<li>Les t\u00e9moins de performance, et<\/li>\n<li>Les t\u00e9moins pour une publicit\u00e9 cibl\u00e9e.<\/li>\n<\/ul>\n<p>Ces types de t\u00e9moins sont plus amplement d\u00e9crits dans les sections ci-dessous.<\/p>\n<h4 class=\"wp-block-heading\">6.1<span>\u00a0<\/span><strong>T\u00e9moins strictement n\u00e9cessaires au fonctionnement des sites web<\/strong><\/h4>\n<p>Ces t\u00e9moins sont n\u00e9cessaires au fonctionnement de nos sites Web. Sans eux, ils ne pourraient pas fonctionner. Ils ne peuvent donc pas \u00eatre d\u00e9sactiv\u00e9s. Ils sont g\u00e9n\u00e9ralement \u00e9tablis en tant que r\u00e9ponse \u00e0 des actions que vous avez effectu\u00e9es et qui constituent une demande de services. Ainsi, ces t\u00e9moins permettent notamment d\u2019appliquer vos pr\u00e9f\u00e9rences de consentement, de vous fournir un identifiant de session, pour des protections de s\u00e9curit\u00e9 (par exemple pour distinguer un humain d\u2019un robot, emp\u00eacher des falsifications de session) et d\u2019effectuer de la pr\u00e9vention de la fraude. Vous pouvez configurer votre navigateur afin de bloquer ou \u00eatre inform\u00e9 de l\u2019existence de ces t\u00e9moins, mais certaines parties du site Web seront affect\u00e9es.<\/p>\n<h4 class=\"wp-block-heading\"><strong>6.2 T\u00e9moins de fonctionnalit\u00e9 et de pr\u00e9f\u00e9rences utilisateurs<\/strong><\/h4>\n<p>Ces t\u00e9moins permettent d\u2019am\u00e9liorer et de personnaliser les fonctionnalit\u00e9s de nos sites Web, notamment la m\u00e9morisation de vos param\u00e8tres et pr\u00e9f\u00e9rences pour offrir une exp\u00e9rience personnalis\u00e9e (par exemple m\u00e9moriser les sites visit\u00e9s \u00e0 plusieurs reprises, optimiser la fonction de la barre de recherche interne aux sites Web, m\u00e9moriser les informations sur vos actions effectu\u00e9es lors de votre visite en cours sur nos sites Web, m\u00e9moriser votre langue par d\u00e9faut, votre consentement \u00e0 accepter l\u2019utilisation des t\u00e9moins ou toute autre pr\u00e9f\u00e9rence enregistr\u00e9e). Ils peuvent \u00eatre activ\u00e9s par nous ou par des tiers dont les services sont utilis\u00e9s sur les pages de nos sites Web. Si vous n\u2019acceptez pas ces t\u00e9moins, une partie ou la totalit\u00e9 de ces services risque de ne pas \u00eatre optimale.<\/p>\n<h4 class=\"wp-block-heading\">6.3<span>\u00a0<\/span><strong>T\u00e9moins de r\u00e9seaux sociaux<\/strong><\/h4>\n<p>Ces t\u00e9moins sont activ\u00e9s par les services propos\u00e9s sur les r\u00e9seaux sociaux que nous avons ajout\u00e9s \u00e0 nos sites Web. Les fonctionnalit\u00e9s li\u00e9es aux r\u00e9seaux sociaux (bouton de partage, \u00ab j\u2019aime \u00bb, etc.) vous offrent la possibilit\u00e9 de partager notre contenu avec votre r\u00e9seau et vos connaissances. Ils nous permettent \u00e9galement de suivre votre navigation sur d\u2019autres sites Web et d\u2019\u00e9tablir un profil de vos int\u00e9r\u00eats. Cela peut avoir un impact sur le contenu et les messages affich\u00e9s sur les autres sites internet que vous consultez. Si vous n\u2019autorisez pas ces t\u00e9moins, il se peut que vous ne puissiez pas utiliser ou visualiser ces outils de partage.<\/p>\n<h4 class=\"wp-block-heading\">6.4<span>\u00a0<\/span><strong>T\u00e9moins de performance et d\u2019analytiques<\/strong><\/h4>\n<p>Ces t\u00e9moins nous permettent de d\u00e9terminer le nombre de visites et les sources du trafic, afin de mesurer et d\u2019am\u00e9liorer les performances de nos sites Web. Ils aident \u00e9galement \u00e0 identifier les pages les plus ou les moins visit\u00e9es et \u00e9valuer comment les visiteurs naviguent sur nos sites Web, \u00e0 mieux comprendre les visiteurs afin d\u2019offrir une meilleure exp\u00e9rience sur nos sites Web, conserver votre session en l\u2019\u00e9tat si requis). Toutes les informations collect\u00e9es par ces t\u00e9moins sont agr\u00e9g\u00e9es. Si vous n\u2019acceptez pas ces t\u00e9moins, nous ne serons pas inform\u00e9s de votre visite sur nos sites. Sans eux, nous ne pouvons pas savoir quel contenu est le plus appr\u00e9ci\u00e9 et \u00e0 quelle fr\u00e9quence des visiteurs uniques reviennent sur les sites, ce qui rend difficile l\u2019am\u00e9lioration des informations propos\u00e9es.<\/p>\n<h4 class=\"wp-block-heading\">6.5<span>\u00a0<\/span><strong>T\u00e9moins pour une publicit\u00e9 cibl\u00e9e et de marketing<\/strong><\/h4>\n<p>Ces t\u00e9moins peuvent \u00eatre mis en place par nos partenaires publicitaires. Ils sont bas\u00e9s sur l\u2019identification unique de votre navigateur et de votre appareil. Ils peuvent \u00eatre utilis\u00e9s par ces soci\u00e9t\u00e9s pour \u00e9tablir un profil de vos int\u00e9r\u00eats en enregistrant des donn\u00e9es sur vos consultations de nos sites Web (comme par exemple les pages que vous avez consult\u00e9es, des liens sur lesquels vous avez cliqu\u00e9, du nombre de fois que vous avez vu un message publicitaire, des publicit\u00e9s sur lesquelles vous avez cliqu\u00e9 ainsi que de vos habitudes de navigation et de vos int\u00e9r\u00eats). Ces donn\u00e9es permettent de vous proposer des publicit\u00e9s pertinentes. Si vous n\u2019autorisez pas ces t\u00e9moins, les publicit\u00e9s que vous verrez risquent de manquer de pertinence pour vous. Ces t\u00e9moins sont \u00e9galement utilis\u00e9s par les services assur\u00e9s par des tiers, comme les boutons \u00ab J\u2019aime \u00bb ou \u00ab Partager \u00bb.<\/p>\n<p>Les renseignements recueillis par les t\u00e9moins peuvent \u00e9galement \u00eatre utilis\u00e9s par L\u00e9ger et ses fournisseurs afin de concevoir, am\u00e9liorer ou commercialiser des produits et des services. Ils sont recueillis et conserv\u00e9s sur des serveurs pouvant \u00eatre situ\u00e9s \u00e0 l\u2019ext\u00e9rieur du Canada. Toutefois, ces renseignements ne sont pas partag\u00e9s par L\u00e9ger avec des tiers, sauf dans des circonstances limit\u00e9es d\u00e9crites dans notre Politique de confidentialit\u00e9.<\/p>\n<p>Pour plus de d\u00e9tails sur la mani\u00e8re dont nous traitons vos renseignements personnels, veuillez vous r\u00e9f\u00e9rer \u00e0 notre\u00a0Politique de confidentialit\u00e9.<\/p>\n<h3 class=\"wp-block-heading\">7.0<span>\u00a0<\/span><strong>EST-CE QUE DES TIERS UTILISENT DES T\u00c9MOINS SUR NOS SITES WEB ?<\/strong><\/h3>\n<p>Nous utilisons, ou nous permettons \u00e0 des tiers de placer, des t\u00e9moins qui entrent dans l\u2019une des cat\u00e9gories indiqu\u00e9es ci-dessus. Par exemple, nous utilisons des outils d\u2019analyse de tiers pour surveiller le trafic sur nos sites web.<\/p>\n<h3 class=\"wp-block-heading\">8.0<span>\u00a0<\/span><strong>D\u00c9SACTIVER LES T\u00c9MOINS<\/strong><\/h3>\n<p>Si vous n\u2019acceptez pas l\u2019utilisation de t\u00e9moins qui ne sont pas strictement n\u00e9cessaires, vous pouvez retirer votre consentement \u00e0 leur utilisation en cliquant sur \u00ab\u00a0personnaliser les t\u00e9moins\u00a0\u00bb situ\u00e9 en haut ou en bas de l\u2019\u00e9cran de votre appareil, selon le site Web visit\u00e9. Toutefois, certains services ne fonctionneront pas aussi bien si les t\u00e9moins sont d\u00e9sactiv\u00e9s.<\/p>\n<p>\u00c9galement, la plupart des navigateurs Internet vous permettent de contr\u00f4ler, dans une certaine mesure, la plupart des t\u00e9moins en vous rendant dans leurs param\u00e8tres. Cliquez sur le nom du navigateur qui vous int\u00e9resse pour en savoir plus sur sa gestion des t\u00e9moins :<\/p>\n<ul>\n<li><a href=\"https:\/\/support.google.com\/accounts\/answer\/61416?co=GENIE.Platform%3DDesktop&amp;hl=fr\">Google Chrome<\/a><\/li>\n<li><a href=\"https:\/\/support.microsoft.com\/fr-fr\/windows\/microsoft-edge-donn%C3%A9es-de-navigation-et-confidentialit%C3%A9-bb8174ba-9d73-dcf2-9b4a-c582b4e640dd\">Microsoft Edge<\/a><\/li>\n<li><a href=\"https:\/\/support.mozilla.org\/fr\/kb\/protection-renforcee-contre-pistage-firefox-ordinateur?redirectslug=enable-and-disable-cookies-website-preferences&amp;redirectlocale=en-US\">Mozilla Firefox<\/a><\/li>\n<li><a href=\"https:\/\/support.microsoft.com\/fr-fr\/windows\/supprimer-et-g%C3%A9rer-les-cookies-168dab11-0753-043d-7c16-ede5947fc64d\">Microsoft Internet Explorer<\/a><\/li>\n<li><a href=\"https:\/\/support.apple.com\/fr-ca\/guide\/safari\/sfri40732\/16.1\/mac\/13.0\">Apple Safari<\/a><\/li>\n<\/ul>\n<h3 class=\"wp-block-heading\"><strong>9.0 CONTACTEZ-NOUS<\/strong><\/h3>\n<p>Pour toute question sur la pr\u00e9sente politique, veuillez communiquer avec nous \u00e0 l\u2019adresse<span>\u00a0<\/span><a href=\"mailto:privacyofficer@leger360.com\">privacyofficer@leger360.com<\/a><span>\u00a0<\/span>ou nous \u00e9crire \u00e0\u00a0:<\/p>\n<p>L\u00e9ger Marketing Inc.<br \/>Responsable de la protection de la vie priv\u00e9e<br \/>700-507, Place d\u2019Armes<br \/>Montr\u00e9al (Qu\u00e9bec) H2Y 2W8 Canada<br \/>privacyofficer@leger360.com<br \/>T\u00e9l\u00e9phone : (514) 982-2464<br \/>T\u00e9l\u00e9copieur : (514) 221-4127<\/p>\n<h3 class=\"wp-block-heading\">10.0<strong>\u00a0MODIFICATIONS DE CETTE POLITIQUE<\/strong><\/h3>\n<p>Il se peut que nous mettions \u00e0 jour la pr\u00e9sente politique, conform\u00e9ment aux lois et principes applicables en mati\u00e8re de protection des donn\u00e9es et de la vie priv\u00e9e. Nous vous encourageons \u00e0 consulter r\u00e9guli\u00e8rement cette politique pour vous tenir inform\u00e9 de la mani\u00e8re dont nous utilisons les t\u00e9moins.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Politique de gestion des t\u00e9moinsDATE D\u2019ENTR\u00c9E EN VIGUEUR : 7 F\u00c9VRIER 2024 1.0\u00a0D\u00c9CLARATION DE POLITIQUE EN MATI\u00c8RE DE T\u00c9MOINS Marketing L\u00e9ger Inc. et ses filiales (\u00ab L\u00e9ger \u00bb) utilise diff\u00e9rents t\u00e9moins de connexion (aussi appel\u00e9s sous le terme anglais \u00ab cookies \u00bb) ou des technologies similaires sur ses sites Web qui sont n\u00e9cessaires pour leur bon fonctionnement mais aussi pour am\u00e9liorer leur performance, bonifier votre exp\u00e9rience, mesurer l\u2019audience et int\u00e9grer des services permettant d\u2019am\u00e9liorer l\u2019interactivit\u00e9 de ces sites. Si vous naviguez sur ces sites, ces t\u00e9moins seront install\u00e9s sur votre navigateur Web. La pr\u00e9sente Politique sur les t\u00e9moins de connexion explique comment nous utilisons ces t\u00e9moins et s\u2019applique aux sites Web. Elle pr\u00e9cise aussi les types de t\u00e9moins de connexion que nous utilisons, pourquoi nous les utilisons et comment vous pouvez modifier vos pr\u00e9f\u00e9rences en mati\u00e8re de t\u00e9moins de connexion. Nous vous conseillons de lire la pr\u00e9sente politique en parall\u00e8le avec notre\u00a0politique de confidentialit\u00e9\u00a0qui indique comment nous collectons, utilisons et traitons vos renseignements personnels. 2.0\u00a0D\u00c9FINITION \u00ab\u00a0T\u00e9moin de connexion\u00a0\u00bb :\u00a0Un petit fichier texte, contenant des informations, stock\u00e9 dans votre appareil (votre ordinateur, t\u00e9l\u00e9phone cellulaire, tablette, etc.) par un site Web (sur lequel vous vous connectez) et qui est associ\u00e9 \u00e0 un [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","content-type":"","inline_featured_image":false,"footnotes":""},"class_list":["post-19065","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Politique de gestion des t\u00e9moins - Leger<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/leger360.com\/fr\/politique-de-gestion-des-temoins\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de gestion des t\u00e9moins\" \/>\n<meta property=\"og:description\" content=\"Politique de gestion des t\u00e9moinsDATE D\u2019ENTR\u00c9E EN VIGUEUR : 7 F\u00c9VRIER 2024 1.0\u00a0D\u00c9CLARATION DE POLITIQUE EN MATI\u00c8RE DE T\u00c9MOINS Marketing L\u00e9ger Inc. et ses filiales (\u00ab L\u00e9ger \u00bb) utilise diff\u00e9rents t\u00e9moins de connexion (aussi appel\u00e9s sous le terme anglais \u00ab cookies \u00bb) ou des technologies similaires sur ses sites Web qui sont n\u00e9cessaires pour leur bon fonctionnement mais aussi pour am\u00e9liorer leur performance, bonifier votre exp\u00e9rience, mesurer l\u2019audience et int\u00e9grer des services permettant d\u2019am\u00e9liorer l\u2019interactivit\u00e9 de ces sites. Si vous naviguez sur ces sites, ces t\u00e9moins seront install\u00e9s sur votre navigateur Web. La pr\u00e9sente Politique sur les t\u00e9moins de connexion explique comment nous utilisons ces t\u00e9moins et s\u2019applique aux sites Web. Elle pr\u00e9cise aussi les types de t\u00e9moins de connexion que nous utilisons, pourquoi nous les utilisons et comment vous pouvez modifier vos pr\u00e9f\u00e9rences en mati\u00e8re de t\u00e9moins de connexion. Nous vous conseillons de lire la pr\u00e9sente politique en parall\u00e8le avec notre\u00a0politique de confidentialit\u00e9\u00a0qui indique comment nous collectons, utilisons et traitons vos renseignements personnels. 2.0\u00a0D\u00c9FINITION \u00ab\u00a0T\u00e9moin de connexion\u00a0\u00bb :\u00a0Un petit fichier texte, contenant des informations, stock\u00e9 dans votre appareil (votre ordinateur, t\u00e9l\u00e9phone cellulaire, tablette, etc.) par un site Web (sur lequel vous vous connectez) et qui est associ\u00e9 \u00e0 un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/leger360.com\/fr\/politique-de-gestion-des-temoins\/\" \/>\n<meta property=\"og:site_name\" content=\"Leger\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/leger360\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-11T06:52:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/leger360.com\/wp-content\/uploads\/2024\/04\/leger-feature-img-home.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1354\" \/>\n\t<meta property=\"og:image:height\" content=\"872\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@leger360\" \/>\n<meta name=\"twitter:label1\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/leger360.com\\\/fr\\\/politique-de-gestion-des-temoins\\\/\",\"url\":\"https:\\\/\\\/leger360.com\\\/fr\\\/politique-de-gestion-des-temoins\\\/\",\"name\":\"Politique de gestion des t\u00e9moins - Leger\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/leger360.com\\\/fr\\\/#website\"},\"datePublished\":\"2023-11-07T19:36:31+00:00\",\"dateModified\":\"2025-08-11T06:52:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/leger360.com\\\/fr\\\/politique-de-gestion-des-temoins\\\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/leger360.com\\\/fr\\\/politique-de-gestion-des-temoins\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/leger360.com\\\/fr\\\/politique-de-gestion-des-temoins\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/leger360.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de gestion des t\u00e9moins\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/leger360.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/leger360.com\\\/fr\\\/\",\"name\":\"Leger\",\"description\":\"Market Research | Data Analytics\",\"publisher\":{\"@id\":\"https:\\\/\\\/leger360.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/leger360.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/leger360.com\\\/fr\\\/#organization\",\"name\":\"Leger\",\"url\":\"https:\\\/\\\/leger360.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\\\/\\\/leger360.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/leger360.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/2022-Logo-Leger-Blackred-g.png\",\"contentUrl\":\"https:\\\/\\\/leger360.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/2022-Logo-Leger-Blackred-g.png\",\"width\":1195,\"height\":686,\"caption\":\"Leger\"},\"image\":{\"@id\":\"https:\\\/\\\/leger360.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/leger360\\\/\",\"https:\\\/\\\/x.com\\\/leger360\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/leger360\\\/\"],\"description\":\"Leger is one of North America\u2019s fastest-growing market research companies, known for our forward-thinking experts and innovative approaches powered by artificial intelligence (AI) technologies.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Politique de gestion des t\u00e9moins - Leger","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/leger360.com\/fr\/politique-de-gestion-des-temoins\/","og_locale":"fr_CA","og_type":"article","og_title":"Politique de gestion des t\u00e9moins","og_description":"Politique de gestion des t\u00e9moinsDATE D\u2019ENTR\u00c9E EN VIGUEUR : 7 F\u00c9VRIER 2024 1.0\u00a0D\u00c9CLARATION DE POLITIQUE EN MATI\u00c8RE DE T\u00c9MOINS Marketing L\u00e9ger Inc. et ses filiales (\u00ab L\u00e9ger \u00bb) utilise diff\u00e9rents t\u00e9moins de connexion (aussi appel\u00e9s sous le terme anglais \u00ab cookies \u00bb) ou des technologies similaires sur ses sites Web qui sont n\u00e9cessaires pour leur bon fonctionnement mais aussi pour am\u00e9liorer leur performance, bonifier votre exp\u00e9rience, mesurer l\u2019audience et int\u00e9grer des services permettant d\u2019am\u00e9liorer l\u2019interactivit\u00e9 de ces sites. Si vous naviguez sur ces sites, ces t\u00e9moins seront install\u00e9s sur votre navigateur Web. La pr\u00e9sente Politique sur les t\u00e9moins de connexion explique comment nous utilisons ces t\u00e9moins et s\u2019applique aux sites Web. Elle pr\u00e9cise aussi les types de t\u00e9moins de connexion que nous utilisons, pourquoi nous les utilisons et comment vous pouvez modifier vos pr\u00e9f\u00e9rences en mati\u00e8re de t\u00e9moins de connexion. Nous vous conseillons de lire la pr\u00e9sente politique en parall\u00e8le avec notre\u00a0politique de confidentialit\u00e9\u00a0qui indique comment nous collectons, utilisons et traitons vos renseignements personnels. 2.0\u00a0D\u00c9FINITION \u00ab\u00a0T\u00e9moin de connexion\u00a0\u00bb :\u00a0Un petit fichier texte, contenant des informations, stock\u00e9 dans votre appareil (votre ordinateur, t\u00e9l\u00e9phone cellulaire, tablette, etc.) par un site Web (sur lequel vous vous connectez) et qui est associ\u00e9 \u00e0 un [&hellip;]","og_url":"https:\/\/leger360.com\/fr\/politique-de-gestion-des-temoins\/","og_site_name":"Leger","article_publisher":"https:\/\/www.facebook.com\/leger360\/","article_modified_time":"2025-08-11T06:52:25+00:00","og_image":[{"width":1354,"height":872,"url":"https:\/\/leger360.com\/wp-content\/uploads\/2024\/04\/leger-feature-img-home.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@leger360","twitter_misc":{"Estimation du temps de lecture":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/leger360.com\/fr\/politique-de-gestion-des-temoins\/","url":"https:\/\/leger360.com\/fr\/politique-de-gestion-des-temoins\/","name":"Politique de gestion des t\u00e9moins - Leger","isPartOf":{"@id":"https:\/\/leger360.com\/fr\/#website"},"datePublished":"2023-11-07T19:36:31+00:00","dateModified":"2025-08-11T06:52:25+00:00","breadcrumb":{"@id":"https:\/\/leger360.com\/fr\/politique-de-gestion-des-temoins\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/leger360.com\/fr\/politique-de-gestion-des-temoins\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/leger360.com\/fr\/politique-de-gestion-des-temoins\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/leger360.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Politique de gestion des t\u00e9moins"}]},{"@type":"WebSite","@id":"https:\/\/leger360.com\/fr\/#website","url":"https:\/\/leger360.com\/fr\/","name":"Leger","description":"Market Research | Data Analytics","publisher":{"@id":"https:\/\/leger360.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/leger360.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Organization","@id":"https:\/\/leger360.com\/fr\/#organization","name":"Leger","url":"https:\/\/leger360.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/leger360.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/leger360.com\/wp-content\/uploads\/2024\/04\/2022-Logo-Leger-Blackred-g.png","contentUrl":"https:\/\/leger360.com\/wp-content\/uploads\/2024\/04\/2022-Logo-Leger-Blackred-g.png","width":1195,"height":686,"caption":"Leger"},"image":{"@id":"https:\/\/leger360.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/leger360\/","https:\/\/x.com\/leger360","https:\/\/www.linkedin.com\/company\/leger360\/"],"description":"Leger is one of North America\u2019s fastest-growing market research companies, known for our forward-thinking experts and innovative approaches powered by artificial intelligence (AI) technologies."}]}},"_links":{"self":[{"href":"https:\/\/leger360.com\/fr\/wp-json\/wp\/v2\/pages\/19065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/leger360.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/leger360.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/leger360.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/leger360.com\/fr\/wp-json\/wp\/v2\/comments?post=19065"}],"version-history":[{"count":0,"href":"https:\/\/leger360.com\/fr\/wp-json\/wp\/v2\/pages\/19065\/revisions"}],"wp:attachment":[{"href":"https:\/\/leger360.com\/fr\/wp-json\/wp\/v2\/media?parent=19065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}